{"id":906,"count":5,"description":"","link":"https:\/\/www.cheapoair.com\/miles-away\/tag\/oktoberfest\/","name":"Oktoberfest","slug":"oktoberfest","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/tags\/906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts?tags=906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}