{"id":1789,"count":1,"description":"","link":"https:\/\/www.cheapoair.com\/miles-away\/tag\/environment\/","name":"environment","slug":"environment","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/tags\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts?tags=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}