{"id":97227107,"date":"2024-12-20T16:26:51","date_gmt":"2024-12-20T16:26:51","guid":{"rendered":"https:\/\/coawp-admin.fareportal.com\/miles-away\/?p=97227107"},"modified":"2024-12-20T16:26:51","modified_gmt":"2024-12-20T16:26:51","slug":"desenvolviendo-la-navidad-sorprendentes-historias-sobre-tus-tradiciones-favoritas-para-las-fiestas","status":"publish","type":"post","link":"https:\/\/www.cheapoair.com\/miles-away\/desenvolviendo-la-navidad-sorprendentes-historias-sobre-tus-tradiciones-favoritas-para-las-fiestas\/","title":{"rendered":"Desenvolviendo la Navidad: Sorprendentes Historias Sobre Tus Tradiciones Favoritas Para las Fiestas"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">\u00bfAlguna vez te has preguntado por qu\u00e9 el ponche de huevo y la corteza de menta parecen estar por todas partes durante las fiestas navide\u00f1as? \u00bfO por qu\u00e9 grupos de personas se re\u00fanen para cantar villancicos, aun cuando hace un fr\u00edo helador en la calle? Muchas tradiciones navide\u00f1as llevan acompa\u00f1\u00e1ndonos desde hace siglos, mientras que otras son sorprendentemente nuevas. Si bien muchas se originaron en Estados Unidos, la mayor\u00eda viajaron a trav\u00e9s de los oc\u00e9anos antes de convertirse en parte de nuestros ritos para la Navidad.<\/p>\n<p>Emb\u00e1rcate con nosotros en un divertido viaje por todo el planeta para descubrir de d\u00f3nde proceden algunas de tus tradiciones navide\u00f1as favoritas y aprender las historias tras sus or\u00edgenes.<\/p>\n<h2>Ponche de Huevo \u2014 Inglaterra<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226913\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Eggnog.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Eggnog.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Eggnog-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Eggnog-768x461.jpg 768w\" alt=\"Eggnog\" width=\"1000\" height=\"600\" \/><\/p>\n<p>Comencemos con el ponche de huevo, una bebida festiva que la gente o bien adora o la evita como la tarta de frutas (m\u00e1s sobre esto despu\u00e9s). Lo creas o no, el ponche de huevo lleva con nosotros desde la <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-reino-unido-gb\" target=\"_blank\" rel=\"noopener\">Inglaterra<\/a> medieval, donde dio inicio como un \u201cposset,\u201d una bebida caliente y lechosa con huevos y jerez. Estaba considerado un producto sofisticado y un s\u00edmbolo de buena salud.<\/p>\n<p>Cuando el ponche de huevo se abri\u00f3 camino hasta Norteam\u00e9rica en el siglo XVIII, los colonos le a\u00f1adieron su propio giro. Debido a que ten\u00edan acceso a muchas gallinas, vacas y ron barato, la bebida se convirti\u00f3 en un \u00e9xito durante las fiestas invernales. Incluso George Washington tuvo su propia receta de ponche de huevo (\u00a1y era fuerte!). Hoy, puedes disfrutarlo con o sin alcohol&#8230;eso s\u00ed, no te olvides de echarle nuez moscada por encima.<\/p>\n<h2>Cantar Villancicos \u2014 Europa<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226914\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-carolers.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-carolers.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-carolers-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-carolers-768x461.jpg 768w\" alt=\"Christmas carolers\" width=\"1000\" height=\"600\" \/><\/p>\n<p>\u00bfAlguna vez has salido a cantar villancicos o lo has visto en una pel\u00edcula navide\u00f1a? Esta tradici\u00f3n musical se remonta muy atr\u00e1s en el tiempo. Los historiadores creen que los primeros ejemplos se originaron en <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-europa\" target=\"_blank\" rel=\"noopener\">Europa<\/a>, ya que las canciones invernales levantaban el \u00e1nimo de la poblaci\u00f3n durante los fr\u00edos y oscuros meses. Originalmente, la gente cantaba y bailaba por sus aldeas, celebrando los cambios estacionales y pidiendo buena fortuna.<\/p>\n<p>A medida que el cristianismo se propag\u00f3, las canciones tomaron un tono religioso y se a\u00f1adieron a las celebraciones navide\u00f1as. Aunque cantar villancicos de puerta en puerta ha ido desapareciendo poco a poco, todav\u00eda puedes escuchar estas canciones atemporales en servicios eclesi\u00e1sticos y conciertos navide\u00f1os. Cl\u00e1sicos como \u201cNoche de Paz\u201d y \u201cHark, the Herald Angels Sing\u201d siguen siendo grandes favoritos, conectando a la gente a trav\u00e9s de generaciones y m\u00fasica navide\u00f1a compartida. Cantar villancicos es una actividad que persiste en pueblos peque\u00f1os y ciudades donde las comunidades todav\u00eda respetan la tradici\u00f3n.<\/p>\n<h2>Chocolate Caliente\u00a0 \u2014 M\u00e9xico y Espa\u00f1a<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226915\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Hot-cocoa-with-marshmallows.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Hot-cocoa-with-marshmallows.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Hot-cocoa-with-marshmallows-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Hot-cocoa-with-marshmallows-768x461.jpg 768w\" alt=\"Hot cocoa with marshmallows\" width=\"1000\" height=\"600\" \/><\/p>\n<p>Pocas cosas resultan tan reconfortantes como una taza de chocolate caliente en una fr\u00eda noche de invierno. Pero, \u00bfsab\u00edas que las ra\u00edces del chocolate caliente se originaron hace miles de a\u00f1os en M\u00e9xico? Los mayas fueron de los primeros en aprender a amar el chocolate, elaborando esta bebida con granos de cacao, agua y especias como pimientos de chile. Era consistente y amarga, no como la versi\u00f3n m\u00e1s dulce consumida en Estados Unidos.<\/p>\n<p>Los exploradores espa\u00f1oles exportaron el cacao a Europa, y una vez all\u00ed se a\u00f1adi\u00f3 az\u00facar y leche, haciendo del chocolate caliente la bebida que conocemos hoy. Algunos, de hecho, dicen que <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-madrid-mad-espana\" target=\"_blank\" rel=\"noopener\">Madrid<\/a> es el hogar no oficial del chocolate caliente moderno. Pero se trata de una bebida disfrutada en todas partes, con variaciones especiales como el chocolate caliente mexicano especiado con canela y cayena para un comfort adicional. Por supuesto, las cafeter\u00edas y tiendas especializadas contin\u00faan mejorando esta bebida con sabores y a\u00f1adidos de lo m\u00e1s creativos.<\/p>\n<h2>Tarjetas de Felicitaciones Navide\u00f1as \u2014 Inglaterra<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226919\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-cards.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-cards.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-cards-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Christmas-cards-768x461.jpg 768w\" alt=\"Christmas cards\" width=\"1000\" height=\"600\" \/><\/p>\n<p>Enviar felicitaciones navide\u00f1as por correo es una de las pocas tradiciones que dependen m\u00e1s del bol\u00edgrafo que de los p\u00edxeles. Las primera tarjeta de Navidad apareci\u00f3 en Inglaterra en 1843. Fue dise\u00f1ada por John Callcott Horsley, quien imprimi\u00f3 1.000 copias coloreadas a mano y las vendi\u00f3 en <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-londres-lon-reino-unido\" target=\"_blank\" rel=\"noopener\">Londres<\/a>, creando de manera instant\u00e1nea una moda navide\u00f1a como pocas.<\/p>\n<p>La pr\u00e1ctica se propag\u00f3 por los Estados Unidos unas pocas d\u00e9cadas m\u00e1s tarde, gracias al impresor de Boston Louis Prang. En la d\u00e9cada de 1880, su compa\u00f1\u00eda imprim\u00eda millones de cartas cada a\u00f1o. Hoy, las tarjetas navide\u00f1as tienden a ser m\u00e1s personalizadas, incluyendo a menudo fotograf\u00edas, notas escritas a mano y deseos sinceros para el nuevo a\u00f1o. S\u00ed, las felicitaciones digitales son m\u00e1s r\u00e1pidas, pero nada puede compararse a recibir una tarjeta navide\u00f1a de verdad en el correo.<\/p>\n<h2>Casas de Jengibre \u2014 Alemania<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226920\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Gingerbread-house.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Gingerbread-house.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Gingerbread-house-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Gingerbread-house-768x461.jpg 768w\" alt=\"Gingerbread house\" width=\"1000\" height=\"600\" \/><\/p>\n<p>Si alguna vez has construido una casita de jengibre \u2014 o has visto alguna derrumbarse \u2014 entonces eres parte de una dulce tradici\u00f3n originada en <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-alemania-qyg-alemania\" target=\"_blank\" rel=\"noopener\">Alemania<\/a> en los 1800. Inspirados por el cl\u00e1sico cuento de Hansel y Gretel, los pasteleros crearon casitas de jengibre cubiertas de dulce para convertir una historia un tanto t\u00e9trica en una querida actividad para las fiestas.<\/p>\n<p>Las creaciones originales estaban elaboradas a base de galletas especiadas con miel, pero eventualmente el jengibre se impuso por resultar m\u00e1s resistente. Hoy, los concursos y recreaciones de casas de jengibre est\u00e1n por todas partes durante las navidades. En algunas ciudades incluso encontrar\u00e1s versiones a tama\u00f1o real de casas de jengibre expuestas en hoteles o espacios p\u00fablicos&#8230;sin duda, obras maestras de arte comestible. La reposter\u00eda de jengibre se ha expandido a las fiestas de decoraci\u00f3n de galletas, otra divertida tradici\u00f3n navide\u00f1a.<\/p>\n<h2>Corteza de Menta \u2014 Estados Unidos<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226921\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Peppermint-bark.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Peppermint-bark.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Peppermint-bark-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Peppermint-bark-768x461.jpg 768w\" alt=\"Peppermint bark\" width=\"1000\" height=\"600\" \/><\/p>\n<p>A diferencia de otras tradiciones navide\u00f1as cuyas ra\u00edces se remontan a tiempos antiguos, la corteza de menta es una invenci\u00f3n relativamente nueva. Se hizo famosa a finales de la d\u00e9cada de 1990 en Estados Unidos gracias a Chuck Williams, de Williams Sonoma, quien introdujo este dulce como respuesta a una empresa que le ret\u00f3 a crear algo festivo pero aparentemente nost\u00e1lgico.<\/p>\n<p>Elaborada con capas de chocolate negro y blanco y coronado por bastoncillos de caramelo triturados, la corteza de menta fue un \u00e9xito inmediato. Es similar a los <em>mendiants <\/em>franceses, piezas de chocolate con frutos secos y fruta escarchada que forma parte de los tradicionales <em>13 Desserts of Provence <\/em>de <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-francia-fr\" target=\"_blank\" rel=\"noopener\">Francia<\/a>. Hoy, las recetas de corteza de menta abundan por doquier, desde las estanter\u00edas de las tiendas a blogs de reposter\u00eda navide\u00f1a. Algunos pasteleros caseros incluso crean sus propias versiones gourmet usando caramelos de menta o interesantes combinaciones de sabores como peppermint mocha.<\/p>\n<p><em><strong>Tambi\u00e9n Te Podr\u00eda Interesar: <a href=\"https:\/\/www.cheapoair.com\/miles-away\/escapada-navidena-disfruta-de-las-raices-de-la-tradicion-en-estos-6-destinos\/\" target=\"_blank\" rel=\"noopener\">\u00a1Escapada Navide\u00f1a! Disfruta de las Ra\u00edces de la Tradici\u00f3n en Estos Destinos<\/a><\/strong><\/em><\/p>\n<h2>Tarta de Frutas \u2014 Italia y Estados Unidos<\/h2>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-97226922\" src=\"http:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Traditional-Christmas-Fruit-Cake.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Traditional-Christmas-Fruit-Cake.jpg 1000w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Traditional-Christmas-Fruit-Cake-300x180.jpg 300w, https:\/\/coawp-admin.fareportal.com\/miles-away\/wp-content\/uploads\/2024\/12\/Traditional-Christmas-Fruit-Cake-768x461.jpg 768w\" alt=\"Traditional Christmas Fruit Cake\" width=\"1000\" height=\"600\" \/><\/h2>\n<p>La tarta de frutas es sin duda un postre navide\u00f1o de lo m\u00e1s controvertido para muchos: o lo adoras, o lo detestas. Esta tarta densa y repleta de frutas tiene ra\u00edces antiguas que datan de tiempos del Imperio Romano. Su larga duraci\u00f3n en la despensa se debe a que est\u00e1 empapada de bebidas alcoh\u00f3licas como brandy, ron o bourbon.<\/p>\n<p>A lo largo de los a\u00f1os, diferentes pa\u00edses han puesto parte de sus propias tradiciones en la tarta de frutas. En <a href=\"https:\/\/www.cheapoair.com\/es-us\/vuelos\/vuelos-baratos-a-italia-it\" target=\"_blank\" rel=\"noopener\">Italia<\/a>\u00a0la gente come <em>panettone<\/em>, un tierno pan relleno de frutas, mientras que los alemanes disfrutan de una densa tarta cubierta de az\u00facar a la que llaman <em>stollen<\/em>. En Estados Unidos, la tarta de frutas se hizo popular a inicios del siglo XX gracias a los cat\u00e1logos de pedidos por correo. Algunas de estas tartas tan antiguas han sido preservadas como curiosidades. Aunque es posible que hoy se haya convertido en una recurrente broma navide\u00f1a, la tarta de frutas definitivamente lleg\u00f3 para quedarse, y las familias con recetas que han pasado de una generaci\u00f3n a otra contin\u00faan horneando sus propias versiones cada Navidad.<\/p>\n<h2 data-pm-slice=\"1 1 []\"><em>Preguntas Frecuentes:<\/em><\/h2>\n<p><strong>P: \u00bfC\u00f3mo debo conservar el ponche de huevo?<br \/>\n<\/strong>R: El ponche de huevo deber\u00eda ser guardado dentro de la nevera en un contenedor sellado, y consumido entre 3 y 5 d\u00edas. Las versiones compradas en tiendas normalmente duran m\u00e1s debido a que contienen conservantes.<\/p>\n<p><strong>P: \u00bfCu\u00e1ndo es un buen momento para enviar tarjetas de Navidad<\/strong><strong>?<br \/>\n<\/strong>R: Intenta enviar tarjetas navide\u00f1as a comienzos de diciembre para que sea m\u00e1s probable que lleguen a tiempo. Las tarjetas internacionales deber\u00edan ser enviadas incluso antes.<\/p>\n<p><strong>P: \u00bfC\u00f3mo puedo evitar que se me derrumben las casas de jengibre?<br \/>\n<\/strong>R: Usa glaseado real como \u201cpegamento\u201d y deja que cada pieza se seque antes de montarlo todo. Una base resistente ayuda a que la estructura se mantenga intacta.<\/p>\n<p><strong>P: \u00bfCu\u00e1l es la diferencia entre cacao caliente y chocolate caliente?<br \/>\n<\/strong>R: El cacao caliente est\u00e1 hecho a base de polvo de cacao, az\u00facar y leche mientras que el chocolate caliente usa chocolate fundido, lo que hace de \u00e9ste una bebida m\u00e1s dulce y cremosa.<\/p>\n<p><strong>P: \u00bfPor qu\u00e9 la tarta de frutas est\u00e1 ba\u00f1ada en alcohol?<br \/>\n<\/strong>R: El alcohol preserva la tarta de frutas e intensifica su sabor a trav\u00e9s del tiempo, lo que hace que dure meses&#8230;o incluso a\u00f1os.<\/p>\n<p><strong>P: \u00bfPuedes congelar la corteza de menta?<br \/>\n<\/strong>R: S\u00ed, la corteza de menta se congela bien. Almac\u00e9nala en un recipiente sellado con papel encerado entre capas para mantenerla fresca y evitar que se pegue.<\/p>\n<p><em><strong>\u00bfCu\u00e1l es tu tradici\u00f3n navide\u00f1a favorita? \u00bfConoc\u00edas sus or\u00edgenes? \u00a1Nos encantar\u00eda leerte en nuestra secci\u00f3n de comentarios!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te has preguntado por qu\u00e9 el ponche de huevo y la corteza de menta parecen estar por todas partes durante las fiestas navide\u00f1as? \u00bfO por qu\u00e9 grupos de personas se re\u00fanen para cantar villancicos, aun cuando hace un fr\u00edo helador en la calle? Muchas tradiciones navide\u00f1as llevan acompa\u00f1\u00e1ndonos desde hace siglos, mientras que [&hellip;]<\/p>\n","protected":false},"author":576,"featured_media":97227109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3003],"tags":[3112,3061,3103,3193,3063,3064,3100,50],"class_list":["post-97227107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-espanol","tag-alemania","tag-espana","tag-estados-unidos","tag-europa","tag-francia","tag-inglaterra","tag-italia","tag-mexico"],"_links":{"self":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts\/97227107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/users\/576"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/comments?post=97227107"}],"version-history":[{"count":8,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts\/97227107\/revisions"}],"predecessor-version":[{"id":97227116,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/posts\/97227107\/revisions\/97227116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/media\/97227109"}],"wp:attachment":[{"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/media?parent=97227107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/categories?post=97227107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cheapoair.com\/miles-away\/wp-json\/wp\/v2\/tags?post=97227107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}